{"id":341,"count":3,"description":"Outlet: Grandes Marcas a Precios Reducidos\r\nDescubre nuestra secci\u00f3n Outlet, donde la calidad y el ahorro van de la mano. Encuentra ropa de trabajo, calzado de seguridad y accesorios profesionales de marcas reconocidas a precios irresistibles.\r\nAprovecha esta oportunidad \u00fanica para equiparte con productos resistentes, c\u00f3modos y funcionales, ideales para cualquier entorno laboral, sin comprometer tu presupuesto. \u00a1Renueva tu vestuario profesional con nuestras ofertas exclusivas en el Outlet!\r\nPalabras clave integradas : outlet ropa de trabajo, ofertas calzado de seguridad, descuentos vestuario laboral, ropa laboral barata, outlet profesional.","link":"https:\/\/combi-pro.com\/fr\/categorie-de-produits\/outlet\/","name":"Outlet","slug":"outlet","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/combi-pro.com\/fr\/wp-json\/wp\/v2\/product_cat\/341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/combi-pro.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/combi-pro.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/combi-pro.com\/fr\/wp-json\/wp\/v2\/product?product_cat=341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}