{"id":344,"count":18,"description":"Gamme Natura : durabilit\u00e9 et promotion responsable\r\nD\u00e9couvrez notre collection Natura, con\u00e7ue \u00e0 partir de mat\u00e9riaux \u00e9cologiques tels que le coton biologique et les tissus recycl\u00e9s. Ces v\u00eatements promotionnels allient durabilit\u00e9 et style, offrant une option respectueuse de l'environnement sans sacrifier la qualit\u00e9 et la personnalisation. Ils sont parfaits pour les entreprises qui s'engagent en faveur de l'environnement.","link":"https:\/\/combi-pro.com\/fr\/categorie-de-produits\/textile-promotionnel\/gamme-nature\/","name":"Gamme Natura","slug":"gamme-nature","taxonomy":"product_cat","parent":340,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/combi-pro.com\/fr\/wp-json\/wp\/v2\/product_cat\/344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/combi-pro.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/combi-pro.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/combi-pro.com\/fr\/wp-json\/wp\/v2\/product_cat\/340"}],"wp:post_type":[{"href":"https:\/\/combi-pro.com\/fr\/wp-json\/wp\/v2\/product?product_cat=344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}